{"id":4517,"count":1,"description":"","link":"https:\/\/oldwp.civil.ge\/ka\/archives\/tag\/%e1%83%a0%e1%83%94%e1%83%a1%e1%83%9e%e1%83%a3%e1%83%91%e1%83%9a%e1%83%98%e1%83%99%e1%83%90-100","name":"\u10e0\u10d4\u10e1\u10de\u10e3\u10d1\u10da\u10d8\u10d9\u10d0 100","slug":"%e1%83%a0%e1%83%94%e1%83%a1%e1%83%9e%e1%83%a3%e1%83%91%e1%83%9a%e1%83%98%e1%83%99%e1%83%90-100","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/oldwp.civil.ge\/ka\/wp-json\/wp\/v2\/tags\/4517"}],"collection":[{"href":"https:\/\/oldwp.civil.ge\/ka\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/oldwp.civil.ge\/ka\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/oldwp.civil.ge\/ka\/wp-json\/wp\/v2\/posts?tags=4517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}